{"id":5675,"date":"2022-06-24T08:26:13","date_gmt":"2022-06-24T08:26:13","guid":{"rendered":"https:\/\/dori-go.com\/?p=5675"},"modified":"2022-06-24T08:29:10","modified_gmt":"2022-06-24T08:29:10","slug":"hybride-arbeitsmodelle-und-was-sie-bedeuten","status":"publish","type":"post","link":"https:\/\/dori-go.com\/index.php\/hybride-arbeitsmodelle-und-was-sie-bedeuten\/","title":{"rendered":"Hybride Arbeitsmodelle und was sie bedeuten"},"content":{"rendered":"\n<p>Bei hybriden Arbeitsmodellen wird nicht mehr ausschliesslich aus dem B\u00fcro gearbeitet, sondern teilweise von zu Hause aus, von irgendwo auf der Welt oder zu ganz verschiedenen Zeiten. Die Entwicklung in den letzten Monaten zeigt, dass sich die meisten Arbeitnehmer:innen \u2013 ebenso wie die jungen Talente der Generation Z \u2013 genau diese Flexibilit\u00e4t im Job w\u00fcnschen. Die Pandemie hat nicht zuletzt zu einem Umdenken und einer anderen Wertevorstellung der Arbeitnehmer:innen in der Schweiz gef\u00fchrt, die nun auch ein Umdenken vieler Unternehmen fordert.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Die Universit\u00e4t St. Gallen (HSG) befragte F\u00fchrungskr\u00e4fte und HR-Experten aus Schweizer Unternehmen aller Gr\u00f6ssen und Branchen zu hybriden Arbeitsmodellen. Vor der Pandemie setzen laut einer Mitteilung der HSG ca. 35 Prozent der Unternehmen auf hybride Modelle, heute sind es bereits 77 Prozent.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Hybrides Arbeiten ist das \u201eNew Normal\u201c.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Zwei wesentliche Faktoren sind bei der Gestaltung hybrider Arbeitsmodelle relevant: Die Arbeitszeit und der Arbeitsort.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Die <strong>Arbeitszeit <\/strong>l\u00e4sst sich in Abh\u00e4ngigkeit von den Anforderungen des Unternehmens und der jeweiligen Position verschieden gestalten und reicht von klaren Vorgaben der Arbeitszeit \u00fcber teilflexible Modelle mit Kern- und Gleitzeiten bis hin zu v\u00f6llig zeitunabh\u00e4ngigen Modellen, in denen weder eine feste Arbeitszeit noch eine feste Arbeitsdauer festgelegt wird. Gemessen wird der oder die einzelne Mitarbeiter:in ausschliesslich am Ergebnis.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Auch der Arbeitsort l\u00e4sst sich in verschiedenen Flexibilit\u00e4tsstufen gestalten. Im Modell \u201eOffice First\u201c wird die Arbeit im B\u00fcro pr\u00e4feriert und remote Work bildet die Ausnahme. In Teil-flexiblen Modellen gibt es in der Regel festgelegte Anwesenheiten im B\u00fcro, die \u00fcbrige Arbeitszeit kann flexibel an anderen Orten oder im B\u00fcro erfolgen. Diese Wahl wird Arbeitnehmer:Innen im Voll-flexiblen Modell g\u00e4nzlich \u00fcberlassen. Auch das Modell \u201eRemote First\u201c bietet maximale Flexibilit\u00e4t, hier arbeiten die Mitarbeiter:innen vorwiegend im Home Office oder anderswo auf der Welt und kommen nur in Ausnahmen ins B\u00fcro.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Durch die individuelle Gestaltung jedes einzelnen Unternehmens k\u00f6nnen verschiedenste Arbeitsmodelle entstehen.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/dori-go.com\/wp-content\/uploads\/2022\/06\/Blog_Bild_innerhalb.svg\" alt=\"\" class=\"wp-image-5676\"\/><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Die Vorteile hybrider Modelle<\/h3>\n\n\n\n<p><br>Die Vorteile der hybriden Modelle liegen auf der Hand. Die Arbeitenehmer:innen gewinnen je nach Gestaltung in sehr hohem Masse an Flexibilit\u00e4t und damit an Zufriedenheit und Motivation f\u00fcr die Arbeit. Insbesondere bei anspruchsvollen Aufgaben kann die Ruhe im Home-Office zu einer gesteigerten Produktivit\u00e4t f\u00fchren.<br>Bei hoher Flexibilit\u00e4t sind meist nur wenige Arbeitspl\u00e4tze n\u00f6tig, die flexibel von den im B\u00fcro anwesenden Mitarbeitenden genutzt werden k\u00f6nnen. Das spart Kosten ein.<br>Unternehmen, die hybride Arbeitsmodelle anbieten und Ihren Mitarbeitenden eine hohe Flexibilit\u00e4t erm\u00f6glichen, haben einen grossen Vorteil in der Rekrutierung neuer Talente.<br><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Die Herausforderungen<\/h3>\n\n\n\n<p><br>Selbstverst\u00e4ndlich bietet das \u201eNew Normal\u201c nicht nur Vorteile, sondern kann Unternehmen \u2013 insbesondere in der Phase der Implementierung \u2013 vor viele Herausforderungen stellen.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Den wesentlichen Beitrag zu einem funktionierenden und erfolgreichen hybriden Modell leisten die IT-Abteilungen, die HR-Abteilungen und die F\u00fchrungskr\u00e4fte.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Die gesamte IT-Infrastruktur muss auf remote Work umgestellt werden, denn digitale Zusammenarbeit kann nur mit einer gut funktionierenden IT-Landschaft funktionieren, die die Kommunikationskan\u00e4le und den Austausch von Informationen einfach erm\u00f6glicht.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Eine grosse Gefahr ist eine geringe Bindung an das Unternehmen und das Team. Wenn der morgendliche B\u00fcrokaffee oder die gemeinsame Mittagspause entfallen, k\u00f6nnen sich Mitarbeiter:innen schnell ausgeschlossen f\u00fchlen. Die F\u00fchrungskr\u00e4fte und HR-Abteilungen stehen vor der Herausforderung, eine hohe Bindung an das Unternehmen und die Entwicklung eines positiven Teamspirits zu schaffen.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Insgesamt ist bei hybriden Arbeitsmodellen von einem h\u00f6heren Planungs- und Organisationsaufwand f\u00fcr Meetings, B\u00fcrobelegungen und Projektkoordinationen zu rechnen.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Wie man hybride Arbeitsmodelle im Unternehmen einf\u00fchrt.<\/h3>\n\n\n\n<p>Die Hauptvoraussetzung f\u00fcr hybride Arbeitsmodelle und Remote Work im Allgemeinen ist Vertrauen in die Mitarbeitenden.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Es ist sinnvoll, die Arbeitnehmer:innen am Gestaltungsprozess teilhaben zu lassen. Wo wird Flexibilit\u00e4t gew\u00fcnscht und wo ist die N\u00e4he zum B\u00fcro und zum Team erforderlich? Wer hat welche Vorstellungen und wie lassen sich diese realisiere und in klaren \u201eSpielregeln\u201c festhalten?<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Wenn die digitalen Voraussetzungen geschaffen sind, gilt es Informationswege und Strukturen f\u00fcr die Ablage von Daten zu schaffen. Nur so ist sichergestellt, dass die erforderlichen Informationen jedem einfach zur Verf\u00fcgung stehen.<br>Es empfiehlt sich auch digitale Routinemeetings zu planen, um die N\u00e4he zum Team und zum Unternehmen aufrecht zu erhalten. F\u00fcr die weitere operative Ausf\u00fchrung k\u00f6nnen die F\u00fchrungskr\u00e4fte insbesondere in \u201eRemote F\u00fchrung\u201c geschult werden.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br>Gerade zu Beginn kann es sinnvoll sein, neue Flexibilit\u00e4t schrittweise zu implementieren. Wir empfehlen regelm\u00e4ssige Feedbackschleifen mit den Mitarbeitenden.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Ihnen hat der Blogbeitrag gefallen? Empfehlen Sie Ihn gerne weiter und teilen Sie ihn in Ihren Netzwerken.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><br><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size\">Quelle: <\/p>\n\n\n\n<p class=\"has-small-font-size\">https:\/\/hirschtec.eu\/studie-hybride-arbeitsmodelle\/<br>https:\/\/www.humanresourcesmanager.de\/content\/hybride-arbeitsmodelle-strategien-und-tipps\/<br>https:\/\/www.lendis.io\/ratgeber\/hybride-arbeit\/modelle\/<br>https:\/\/www.netzwoche.ch\/news\/2021-11-05\/hybrides-arbeiten-das-sind-die-chancen-und-risiken<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei hybriden Arbeitsmodellen wird nicht mehr ausschliesslich aus dem B\u00fcro gearbeitet, sondern teilweise von zu Hause aus, von irgendwo auf der Welt oder zu ganz verschiedenen Zeiten. Die Entwicklung in den letzten Monaten zeigt, dass sich die meisten Arbeitnehmer:innen \u2013 ebenso wie die jungen Talente der Generation Z \u2013 genau diese Flexibilit\u00e4t im Job w\u00fcnschen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[66],"tags":[],"class_list":["post-5675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-change-management","entry","has-media"],"_links":{"self":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/5675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/comments?post=5675"}],"version-history":[{"count":6,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/5675\/revisions"}],"predecessor-version":[{"id":5688,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/5675\/revisions\/5688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/media\/5678"}],"wp:attachment":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/media?parent=5675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/categories?post=5675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/tags?post=5675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}