{"id":4201,"date":"2021-03-05T06:05:51","date_gmt":"2021-03-05T06:05:51","guid":{"rendered":"https:\/\/dori-go.com\/?p=4201"},"modified":"2022-01-20T11:05:45","modified_gmt":"2022-01-20T11:05:45","slug":"die-candidate-experience-und-3-tipps-zur-optimierung","status":"publish","type":"post","link":"https:\/\/dori-go.com\/index.php\/die-candidate-experience-und-3-tipps-zur-optimierung\/","title":{"rendered":"Die Candidate Experience und 3 Tipps zur Optimierung"},"content":{"rendered":"\n<p>Wer von &#171;Candidate Experience&#187; spricht meint die Summe aller Eindr\u00fccke und Erfahrungen, die ein Jobsuchender \u00fcber einen potentiellen Arbeitgeber w\u00e4hrend des gesamten Informations-, Bewerbungs- und ggf. auch Onboardingprozesses gewinnt.<\/p>\n\n\n\n<p>Um der Candidate Experience auf den Grund zu gehen und diese aktiv gestalten zu k\u00f6nnen, teilt man sie \u00fcblicherweise in 6 Phasen auf, die wir untenstehend etwas n\u00e4her beleuchten:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Die Phase der Anziehung<br>In dieser Phase geht es darum, die Aufmerksamkeit des potentiellen Bewerbers zu erhalten. Dies kann klassisch durch eine Stellenanzeige geschehen, aber auch auf verschiedensten anderen Wegen, wie zum Beispiel durch die Ansprache mit Hilfe eines externen Recruiters.<br><br><\/li><li>Informationsphase<br>Ist die erste H\u00fcrde geschafft und Sie haben die Aufmerksamkeit des potentiellen Kandidaten, so wird er oder sie sich in der n\u00e4chsten Phase weiter \u00fcber Ihr Unternehmen und einen potentiell passenden Job informieren. Hierbei spielen Ihre Webseite, Ihr gesamter Online-Auftritt und auch Gespr\u00e4che, beispielsweise mit bestehenden Mitarbeitern oder Kunden, eine Rolle.<\/li><\/ol>\n\n\n\n<p>Gem\u00e4\u00df einer Studie von IBM haben 48 % der Kandidaten bereits vor der Bewerbung einen Kontakt oder eine Beziehung zu dem Unternehmen, in dem sie sich dann bewerben. Dies kann ganz verschiedener Natur sein. Familie oder Freunde arbeiten bereits f\u00fcr das Unternehmen, der Bewerber kennt die Marke &#8211; ist vielleicht Kunde des Unternehmens oder arbeitet(e) f\u00fcr einen Mitbewerber. Kaum ein potentieller Bewerber, der einmal einen weniger positiven Eindruck \u00fcber das Unternehmen gewonnen hat, wird sich bewerben. Dies verdeutlicht die hohe Relevanz der ersten beiden Phasen.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><li>Die Phase der Bewerbung<br>Haben Sie Ihren potentiellen Kandidaten in den ersten beiden Phasen \u00fcberzeugen k\u00f6nnen, wird er oder sie sich jetzt mit Ihren Anforderungen an eine Bewerbung und dem Bewerbungsprozess auseinandersetzen. &#171;Keep it simple&#187; ist hier eine der besten Empfehlungen. Ein einfaches und \u00fcbersichtliches Bewerbungsformular mit einem gut funktionierenden Dateiupload sind das A und O in der dritten Phase und best\u00e4tigen Ihre Kandidaten in dem Wunsch f\u00fcr Ihr Unternehmen t\u00e4tig werden zu wollen.<\/li><\/ol>\n\n\n\n<p>Die Dorigo AG bieten Ihren Bewerbern zum Beispiel unter jeder Ausschreibung unmittelbar die M\u00f6glichkeit zur Online-Bewerbung. Die Formulare sind denkbar einfach gehalten. Initiativbewerbungen erm\u00f6glichen wir einfach und zweckm\u00e4ssig \u00fcber unser <a href=\"https:\/\/dori-go.com\/index.php\/kontakt\/\" class=\"rank-math-link\">Kontaktformular<\/a>. <\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\"><li>Die Auswahlphase<br>In dieser Phase kommt es nun das erste Mal zu einem Kontakt zwischen Ihrem Unternehmen und dessen Kultur und den Kandidaten. In die Auswahlphase geh\u00f6ren Vorab-Telefonate, der Empfang im Unternehmen, das Bewerbungsgespr\u00e4ch oder Videointerview und auch der Kontakt im Nachgang. Denke Sie immer daran, dass auch ein Bewerber, der Sie f\u00fcr diese Stelle vielleicht nicht \u00fcberzeugt hat auch in Zukunft interessant f\u00fcr eine Position in Ihrem Unternehmen werden kann. Wichtig sind hier insbesondere pers\u00f6nliche R\u00fcckmeldungen (im Gegensatz zu  Standardtexten) sowie Ihre Reaktionsgeschwindigkeit und Informationstransparenz.<br><br><\/li><li>Onboarding<br>Stellen Sie in Ihrem Onboardingprozess sicher, dass die Kultur des Unternehmens, die den Kandidaten \u00fcberzeugt hat, mit der Einstellung nicht zu Ende geht. Der Onboarding-Prozess soll Ihrem neuen Mitarbeitenden den Einstieg in das Unternehmen erleichtern und den Kandidaten in der Wahl seines neuen Arbeitgebers best\u00e4tigen.<br><br><\/li><li>Bindung<br>Die letzte Phase beschreibt die Zeit, bis der Kandidat sich als fester Bestandteil des Unternehmens wahrnimmt und entsprechend integriert ist. Solange der neue Mitarbeitende auch noch als solcher behandelt und gesehen wird, also als &#171;Neuling&#187;, spricht man von der Bindungsphase.<\/li><\/ol>\n\n\n\n<p>Haben Sie sich schon einmal die Zeit genommen, die Reise Ihres potentiellen Bewerbers zu analysieren, bis er zum fest integrierten Mitarbeitenden geworden ist? Nur wenn Sie die Candidate Experience Ihres Unternehmens wirklich kennen, k\u00f6nnen Sie sie optimieren und davon profitieren.<\/p>\n\n\n\n<p>Eine durchdachte und positive Candidate Experience f\u00fchrt zu:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Einer h\u00f6heren Arbeitgeberattraktivit\u00e4t. Ihre Bewerber bleiben im Bewerbungsprozess und m\u00f6chten f\u00fcr Ihr Unternehmen arbeiten.<\/li><li>Einem funktionierenden und sehr wertvollem Empfehlungsmarketing im Recruiting. Ihre Bewerber \u00e4ussern sich positiv \u00fcber Ihr Unternehmen und den Kontakt mit Ihnen und das sogar unabh\u00e4ngig vom letztendlichen Ergebnis des eignen Bewerbungsprozesses.<\/li><li>Einer gest\u00e4rkten Arbeitgebermarke, die sich positiv auf das gesamte Image Ihres Unternehmens und Ihrer Produkte auswirkt.<\/li><\/ul>\n\n\n\n<p><strong>3 Tipps um Ihre Candidate Experience zu optimieren.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Entwickeln Sie eine Candidate Persona: Welchen Charakter hat Ihr perfekter Bewerber oder Ihre perfekte Bewerberin? Welche Ziele verfolgt er oder sie beruflich wie privat? Was f\u00fchrt zu Frustration? Welche Motive haben Ihre optimalen Kandidaten und welche Kommunikationskan\u00e4le nutzen sie? Was zieht sie an und was schreckt sie ab? Bei Bedarf unterst\u00fctzen wir Sie hier mit unserem Modul zum <a href=\"https:\/\/dori-go.com\/index.php\/fur-kunden\/executive-search-rekrutierung\/#executivesearch-1\" class=\"rank-math-link\">Soll-Profil<\/a>.<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Analysieren Sie die Touchpoints: Welche Kontaktpunkte haben potentielle Bewerber und Kandidaten in den einzelnen Phasen? Was l\u00e4uft hier aus Sicht der Kandidaten gut und wo l\u00e4sst sich etwas optimieren? Denken Sie ab Phase 3 insbesondere an die Informationstransparenz. Weiss Ihr Bewerber zu jeder Zeit in welcher Phase er sich befindet, wie der weitere Prozess aussieht und in welchem Zeitraum er oder sie mit einem Feedback oder dem n\u00e4chsten Schritt rechnen kann? Denken Sie an pers\u00f6nliche Mitteilungen, niemand wird gerne mit einer Standard-Information ohne pers\u00f6nlich Note vertr\u00f6stet.<br><br><\/li><li>Eine wirklich erfolgreiche Candidate Experience bindet HR-Ressourcen und erfordert in den verschiedenen Phasen ganz unterschiedliche Kompetenzen. Wenn Ihnen diese nicht zur Verf\u00fcgung stehen, sollten Sie dar\u00fcber nachdenken, Teilbereiche an externe Dienstleister \u00fcbergeben, die sich hier spezialisiert haben. <a href=\"https:\/\/dori-go.com\/index.php\/kontakt\/\" class=\"rank-math-link\">Wir bieten Ihnen dazu ein modulares Outsourcing-Konzept und stehen Ihnen auch gerne beratend zur Verf\u00fcgung<\/a>. <\/li><\/ol>\n\n\n\n<p style=\"font-size:11px\"><em><br><br>Quellen: <\/em><\/p>\n\n\n\n<p style=\"font-size:11px\">https:\/\/www.hansalog.de\/blog\/7-tipps-fuer-eine-positive-candidate-experience.html<br>https:\/\/www.personio.de\/hr-lexikon\/candidate-experience-definition\/<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer von &#171;Candidate Experience&#187; spricht meint die Summe aller Eindr\u00fccke und Erfahrungen, die ein Jobsuchender \u00fcber einen potentiellen Arbeitgeber w\u00e4hrend des gesamten Informations-, Bewerbungs- und ggf. auch Onboardingprozesses gewinnt. Um der Candidate Experience auf den Grund zu gehen und diese aktiv gestalten zu k\u00f6nnen, teilt man sie \u00fcblicherweise in 6 Phasen auf, die wir untenstehend [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[63,65,62],"tags":[],"class_list":["post-4201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-executive-search","category-development","category-unternehmen","entry","has-media"],"_links":{"self":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/4201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/comments?post=4201"}],"version-history":[{"count":5,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/4201\/revisions"}],"predecessor-version":[{"id":4212,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/posts\/4201\/revisions\/4212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/media\/5345"}],"wp:attachment":[{"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/media?parent=4201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/categories?post=4201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dori-go.com\/index.php\/wp-json\/wp\/v2\/tags?post=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}